{"id":116,"date":"2016-03-25T10:13:59","date_gmt":"2016-03-25T13:13:59","guid":{"rendered":"http:\/\/www.ilheusnoticias.net.br\/v1\/?p=116"},"modified":"2016-03-25T10:13:59","modified_gmt":"2016-03-25T13:13:59","slug":"prefeitura-de-itabuna-abre-concurso-publico","status":"publish","type":"post","link":"https:\/\/www.ilheusnoticias.net.br\/v1\/2016\/03\/25\/prefeitura-de-itabuna-abre-concurso-publico\/","title":{"rendered":"Prefeitura de Itabuna abre concurso p\u00fablico"},"content":{"rendered":"<h2 class=\"PostHeaderIcon-wrapper\"><\/h2>\n<div class=\"PostContent\">\n<p><a href=\"http:\/\/www.agravo.blog.br\/wp-content\/uploads\/2016\/03\/concursopublico-full-2016.jpg\"><img loading=\"lazy\" class=\"aligncenter  wp-image-47922\" src=\"http:\/\/www.agravo.blog.br\/wp-content\/uploads\/2016\/03\/concursopublico-full-2016.jpg\" alt=\"concursopublico-full-2016\" width=\"526\" height=\"64\" \/><\/a><\/p>\n<p>A edi\u00e7\u00e3o online n\u00ba 1.470 do Di\u00e1rio Oficial do Munic\u00edpio, de ontem, quinta-feira, 24, publica Edital do Concurso P\u00fablico (01\/2016) visando o provimento de 617 cargos efetivos do quadro de servidores da Prefeitura de Itabuna. As inscri\u00e7\u00f5es est\u00e3o abertas a partir de hoje at\u00e9 o dia 17 de abril e devem ser feitas exclusivamente via internet no endere\u00e7o da Funda\u00e7\u00e3o Professor Carlos Augusto Bittencourt (<a href=\"http:\/\/www.agravo.blog.br\/www.funcab.org\" target=\"_blank\"><strong>www.funcab.org<\/strong><\/a>). Os valores das taxas s\u00e3o os seguintes: R$ 50,00 para os cargos de Ensino Fundamental; R$ 80,00 para os de Ensino M\u00e9dio e T\u00e9cnico; e R$ 100,00 para os de Ensino Superior.<\/p>\n<p>Doadores de sangue ou candidato inscrito no Cadastro \u00danico para Programas Sociais do Governo Federal (Cad\u00danico) e membro de fam\u00edlia de baixa renda poder\u00e3o solicitar a isen\u00e7\u00e3o do pagamento da taxa, desde que as condi\u00e7\u00f5es sejam comprovadas. Ao efetuar a inscri\u00e7\u00e3o via Internet, o candidato dever\u00e1 imprimir o boleto banc\u00e1rio e efetuar o pagamento do valor da inscri\u00e7\u00e3o at\u00e9 a data do seu vencimento em ag\u00eancia banc\u00e1ria ou casa lot\u00e9rica. Caso o pagamento n\u00e3o seja efetuado, dever\u00e1 acessar o site www.funcab.org e emitir a 2\u00aa via do boleto banc\u00e1rio, que ter\u00e1 nova data de vencimento.<\/p>\n<p>De acordo com o calend\u00e1rio divulgado, as provas objetivas e discursivas ser\u00e3o realizadas no dia 8 de maio. No dia 30 daquele m\u00eas, a Funda\u00e7\u00e3o Professor Carlos Augusto Bittencourt convocar\u00e1 os candidatos classificados para provas pr\u00e1ticas para os casos em que as fun\u00e7\u00f5es exigem esta nova etapa, que ocorrer\u00e3o nos dias 4 e 5 de junho. O resultado final do concurso est\u00e1 previsto para ser divulgado at\u00e9 o dia 23 de junho.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A edi\u00e7\u00e3o online n\u00ba 1.470 do Di\u00e1rio Oficial do Munic\u00edpio, de ontem, quinta-feira, 24, publica Edital do Concurso P\u00fablico (01\/2016) visando o provimento de 617 cargos efetivos do quadro de servidores da Prefeitura de Itabuna. As inscri\u00e7\u00f5es est\u00e3o abertas a partir de hoje at\u00e9 o dia 17 de abril e devem ser feitas exclusivamente via [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ilheusnoticias.net.br\/v1\/wp-json\/wp\/v2\/posts\/116"}],"collection":[{"href":"https:\/\/www.ilheusnoticias.net.br\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilheusnoticias.net.br\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilheusnoticias.net.br\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilheusnoticias.net.br\/v1\/wp-json\/wp\/v2\/comments?post=116"}],"version-history":[{"count":1,"href":"https:\/\/www.ilheusnoticias.net.br\/v1\/wp-json\/wp\/v2\/posts\/116\/revisions"}],"predecessor-version":[{"id":117,"href":"https:\/\/www.ilheusnoticias.net.br\/v1\/wp-json\/wp\/v2\/posts\/116\/revisions\/117"}],"wp:attachment":[{"href":"https:\/\/www.ilheusnoticias.net.br\/v1\/wp-json\/wp\/v2\/media?parent=116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilheusnoticias.net.br\/v1\/wp-json\/wp\/v2\/categories?post=116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilheusnoticias.net.br\/v1\/wp-json\/wp\/v2\/tags?post=116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}